{"id":9,"count":4,"description":"","link":"https:\/\/demos.exotecnologia.com.ve\/isamica\/tag\/gallery\/","name":"Gallery","slug":"gallery","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/demos.exotecnologia.com.ve\/isamica\/wp-json\/wp\/v2\/tags\/9"}],"collection":[{"href":"https:\/\/demos.exotecnologia.com.ve\/isamica\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/demos.exotecnologia.com.ve\/isamica\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/demos.exotecnologia.com.ve\/isamica\/wp-json\/wp\/v2\/posts?tags=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}