{"id":2,"date":"2024-03-27T19:28:43","date_gmt":"2024-03-27T23:28:43","guid":{"rendered":"https:\/\/demos.exotecnologia.com.ve\/isamica\/?page_id=2"},"modified":"2024-03-27T19:28:43","modified_gmt":"2024-03-27T23:28:43","slug":"pagina-ejemplo","status":"publish","type":"page","link":"https:\/\/demos.exotecnologia.com.ve\/isamica\/pagina-ejemplo\/","title":{"rendered":"P\u00e1gina de ejemplo"},"content":{"rendered":"\n<p>Esta es una p\u00e1gina de ejemplo. Es diferente a una entrada del blog porque permanecer\u00e1 en un solo lugar y aparecer\u00e1 en la navegaci\u00f3n de tu sitio (en la mayor\u00eda de los temas). La mayor\u00eda de las personas comienzan con una p\u00e1gina \u00abAcerca de\u00bb que les presenta a los visitantes potenciales del sitio. Podr\u00edas decir algo as\u00ed:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>\u00a1Bienvenido! Soy camarero de d\u00eda, aspirante a actor de noche y esta es mi web. Vivo en Mairena del Alcor, tengo un perro que se llama Firulais y me gusta el rebujito. (Y las tardes largas con caf\u00e9).<\/p><\/blockquote>\n\n\n\n<p>\u2026o algo as\u00ed:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>La empresa \u00abMariscos Recio\u00bb fue fundada por Antonio Recio Mata. Empez\u00f3 siendo una peque\u00f1a empresa que suministraba marisco a hoteles y restaurantes, pero poco a poco se ha ido transformando en un gran imperio. Mariscos Recio, el mar al mejor precio.<\/p><\/blockquote>\n\n\n\n<p>Como nuevo usuario de WordPress, deber\u00edas ir a <a href=\"https:\/\/demos.exotecnologia.com.ve\/isamica\/wp-admin\/\">tu escritorio<\/a> para borrar esta p\u00e1gina y crear nuevas p\u00e1ginas para tu contenido. \u00a1P\u00e1salo bien!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta es una p\u00e1gina de ejemplo. Es diferente a una entrada del blog porque permanecer\u00e1 en un solo lugar y aparecer\u00e1 en la navegaci\u00f3n de tu sitio (en la mayor\u00eda de los temas). La mayor\u00eda de las personas comienzan con una p\u00e1gina \u00abAcerca de\u00bb que les presenta a los visitantes potenciales del sitio. Podr\u00edas decirLeer M\u00e1s<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/demos.exotecnologia.com.ve\/isamica\/wp-json\/wp\/v2\/pages\/2"}],"collection":[{"href":"https:\/\/demos.exotecnologia.com.ve\/isamica\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demos.exotecnologia.com.ve\/isamica\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demos.exotecnologia.com.ve\/isamica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demos.exotecnologia.com.ve\/isamica\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":0,"href":"https:\/\/demos.exotecnologia.com.ve\/isamica\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"wp:attachment":[{"href":"https:\/\/demos.exotecnologia.com.ve\/isamica\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}